{"id":118493,"date":"2022-11-18T01:18:09","date_gmt":"2022-11-18T01:18:09","guid":{"rendered":"https:\/\/dev.museumtv.art\/?post_type=program&#038;p=118493"},"modified":"2025-12-29T06:12:26","modified_gmt":"2025-12-29T06:12:26","slug":"20526-cesar-pauvre-s00-e54","status":"publish","type":"program","link":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/","title":{"rendered":"Cesar Pauvre"},"content":{"rendered":"<p>C\u00e9sar comes from a very modest background, to be able to express all his creativity. He had to find an economical way to provide himself with raw material.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e9sar comes from a very modest background, to be able to express all his creativity.<\/p>\n","protected":false},"featured_media":146796,"parent":0,"menu_order":0,"template":"","format":"standard","meta":[],"program_type":[15],"group":[545],"d_category":[661],"genre":[2492],"class_list":["post-118493","program","type-program","status-publish","format-standard","has-post-thumbnail","hentry","program_type-episode","group-decryptage","d_category-actualites","genre-entertainement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cesar Pauvre - Museum TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cesar Pauvre - Museum TV\" \/>\n<meta property=\"og:description\" content=\"C\u00e9sar comes from a very modest background, to be able to express all his creativity.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/\" \/>\n<meta property=\"og:site_name\" content=\"Museum TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/museumtv.art\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-29T06:12:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.museumtv.art\/wp-content\/uploads\/2023\/05\/art-news-season-cesar-pauvre64552f067d22c.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/\",\"url\":\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/\",\"name\":\"Cesar Pauvre - Museum TV\",\"isPartOf\":{\"@id\":\"https:\/\/www.museumtv.art\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.museumtv.art\/wp-content\/uploads\/2023\/05\/art-news-season-cesar-pauvre64552f067d22c.jpeg\",\"datePublished\":\"2022-11-18T01:18:09+00:00\",\"dateModified\":\"2025-12-29T06:12:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#primaryimage\",\"url\":\"https:\/\/www.museumtv.art\/wp-content\/uploads\/2023\/05\/art-news-season-cesar-pauvre64552f067d22c.jpeg\",\"contentUrl\":\"https:\/\/www.museumtv.art\/wp-content\/uploads\/2023\/05\/art-news-season-cesar-pauvre64552f067d22c.jpeg\",\"width\":1920,\"height\":1080,\"caption\":\"C\u00e9sar comes from a very modest background, to be able to express all his creativity.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.museumtv.art\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programs\",\"item\":\"https:\/\/www.museumtv.art\/programs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cesar Pauvre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.museumtv.art\/#website\",\"url\":\"https:\/\/www.museumtv.art\/\",\"name\":\"Museum TV\",\"description\":\"The first channel dedicated to art\",\"publisher\":{\"@id\":\"https:\/\/www.museumtv.art\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.museumtv.art\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.museumtv.art\/#organization\",\"name\":\"Museum TV\",\"url\":\"https:\/\/www.museumtv.art\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.museumtv.art\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.museumtv.art\/wp-content\/uploads\/2021\/10\/apple-touch-icon-1.png\",\"contentUrl\":\"https:\/\/www.museumtv.art\/wp-content\/uploads\/2021\/10\/apple-touch-icon-1.png\",\"width\":180,\"height\":180,\"caption\":\"Museum TV\"},\"image\":{\"@id\":\"https:\/\/www.museumtv.art\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/museumtv.art\/\",\"https:\/\/www.instagram.com\/museumtv_art\/?hl=fr\",\"https:\/\/www.linkedin.com\/company\/museumtv\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cesar Pauvre - Museum TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/","og_locale":"en_US","og_type":"article","og_title":"Cesar Pauvre - Museum TV","og_description":"C\u00e9sar comes from a very modest background, to be able to express all his creativity.","og_url":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/","og_site_name":"Museum TV","article_publisher":"https:\/\/www.facebook.com\/museumtv.art\/","article_modified_time":"2025-12-29T06:12:26+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.museumtv.art\/wp-content\/uploads\/2023\/05\/art-news-season-cesar-pauvre64552f067d22c.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/","url":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/","name":"Cesar Pauvre - Museum TV","isPartOf":{"@id":"https:\/\/www.museumtv.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#primaryimage"},"image":{"@id":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#primaryimage"},"thumbnailUrl":"https:\/\/www.museumtv.art\/wp-content\/uploads\/2023\/05\/art-news-season-cesar-pauvre64552f067d22c.jpeg","datePublished":"2022-11-18T01:18:09+00:00","dateModified":"2025-12-29T06:12:26+00:00","breadcrumb":{"@id":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#primaryimage","url":"https:\/\/www.museumtv.art\/wp-content\/uploads\/2023\/05\/art-news-season-cesar-pauvre64552f067d22c.jpeg","contentUrl":"https:\/\/www.museumtv.art\/wp-content\/uploads\/2023\/05\/art-news-season-cesar-pauvre64552f067d22c.jpeg","width":1920,"height":1080,"caption":"C\u00e9sar comes from a very modest background, to be able to express all his creativity."},{"@type":"BreadcrumbList","@id":"https:\/\/www.museumtv.art\/en\/program\/20526-cesar-pauvre-s00-e54\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.museumtv.art\/en\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/www.museumtv.art\/programs\/"},{"@type":"ListItem","position":3,"name":"Cesar Pauvre"}]},{"@type":"WebSite","@id":"https:\/\/www.museumtv.art\/#website","url":"https:\/\/www.museumtv.art\/","name":"Museum TV","description":"The first channel dedicated to art","publisher":{"@id":"https:\/\/www.museumtv.art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museumtv.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.museumtv.art\/#organization","name":"Museum TV","url":"https:\/\/www.museumtv.art\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.museumtv.art\/#\/schema\/logo\/image\/","url":"https:\/\/www.museumtv.art\/wp-content\/uploads\/2021\/10\/apple-touch-icon-1.png","contentUrl":"https:\/\/www.museumtv.art\/wp-content\/uploads\/2021\/10\/apple-touch-icon-1.png","width":180,"height":180,"caption":"Museum TV"},"image":{"@id":"https:\/\/www.museumtv.art\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/museumtv.art\/","https:\/\/www.instagram.com\/museumtv_art\/?hl=fr","https:\/\/www.linkedin.com\/company\/museumtv"]}]}},"status_options":[{"label":"Inactive","value":"inactive"}],"_links":{"self":[{"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/programs\/118493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/programs"}],"about":[{"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/media\/146796"}],"wp:attachment":[{"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/media?parent=118493"}],"wp:term":[{"taxonomy":"program_type","embeddable":true,"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/program_type?post=118493"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/group?post=118493"},{"taxonomy":"d_category","embeddable":true,"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/d_category?post=118493"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.museumtv.art\/en\/wp-json\/wp\/v2\/genre?post=118493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}